{"id":4700,"date":"2025-07-31T18:14:30","date_gmt":"2025-07-31T10:14:30","guid":{"rendered":"https:\/\/www.moonepc.com\/?p=4700"},"modified":"2025-08-26T10:51:08","modified_gmt":"2025-08-26T02:51:08","slug":"seafoods","status":"publish","type":"post","link":"https:\/\/www.moonepc.com\/es\/solution\/seafoods\/","title":{"rendered":"Mariscos"},"content":{"rendered":"<p>El procesamiento congelado de mariscos se refiere al proceso de congelaci\u00f3n de peces, camarones, crust\u00e1ceos, mariscos y moluscos cultivados o capturados en agua marina y agua dulce para su conservaci\u00f3n. MOON-TECH ofrece un servicio de paquete que incluye planificaci\u00f3n de proyectos, dise\u00f1o, suministro, instalaci\u00f3n, puesta en marcha, capacitaci\u00f3n y servicio posventa, proporcionando un proyecto llave en mano perfecto para los clientes de procesamiento de mariscos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El procesamiento congelado de mariscos se refiere al proceso de congelaci\u00f3n de peces, camarones, crust\u00e1ceos, mariscos y moluscos cultivados o capturados en agua marina y agua dulce para su conservaci\u00f3n. MOON-TECH ofrece un servicio de paquete que incluye planificaci\u00f3n de proyectos, dise\u00f1o, suministro, instalaci\u00f3n, puesta en marcha, capacitaci\u00f3n y servicio posventa, proporcionando un proyecto llave en mano perfecto para los clientes de procesamiento de mariscos.<\/p>","protected":false},"author":1,"featured_media":5722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,27],"tags":[],"class_list":["post-4700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solution","category-food-logistics-deep-processing"],"acf":{"photo_gallery":{"\u56fe\u7247\u5c55\u793a":[[]]}},"_links":{"self":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/4700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/comments?post=4700"}],"version-history":[{"count":7,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/4700\/revisions"}],"predecessor-version":[{"id":5549,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/4700\/revisions\/5549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/media\/5722"}],"wp:attachment":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/media?parent=4700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/categories?post=4700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/tags?post=4700"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}