{"id":5518,"date":"2025-08-13T10:46:09","date_gmt":"2025-08-13T02:46:09","guid":{"rendered":"https:\/\/www.moonepc.com\/?p=5518"},"modified":"2025-08-13T10:50:20","modified_gmt":"2025-08-13T02:50:20","slug":"ccus","status":"publish","type":"post","link":"https:\/\/www.moonepc.com\/es\/solution\/ccus\/","title":{"rendered":"CCUS"},"content":{"rendered":"<p>El procesamiento de gases industriales requiere compresores y unidades de refrigeraci\u00f3n para gases como el SO \u2082, CO\u2082, y Cl \u2082, La demanda del mercado se mantiene relativamente estable. En los \u00faltimos a\u00f1os, con el aumento de las temperaturas globales, los pa\u00edses de todo el mundo han propuesto sucesivamente metas de pico de carbono y neutralidad de carbono, impulsando el r\u00e1pido crecimiento de la industria CCUS (Captura, Utilizaci\u00f3n y Almacenamiento de Carbono). Antes de esto, nuestra empresa ha desarrollado y aplicado tecnolog\u00edas relacionadas con CCUS durante m\u00e1s de 20 a\u00f1os, acumulando profundas reservas t\u00e9cnicas.<br \/>\nNuestra empresa ha construido una planta de licuaci\u00f3n con una capacidad anual de 150.000 toneladas de di\u00f3xido de carbono, recuperando gas de cola qu\u00edmico de Wanhua Chemical para producir CO de grado alimentario e industrial \u2082.<br \/>\nDentro de este nicho de mercado, nuestros productos y sistemas son ampliamente aplicados, como el primer proyecto CCUS de China para la recuperaci\u00f3n mejorada de petr\u00f3leo: el proyecto de la planta petroqu\u00edmica del campo petrol\u00edfero de Zhongyuan; as\u00ed como proyectos notables como Shanghai Petrochemical Iwatani Gas Development Co., Ltd. (proveedor de Coca-Cola), Sinopec Huayang Liquid CO. \u2082  proyectos de serie, proyecto del campo petrol\u00edfero de CNPC Hainan Fushan, proyectos de la serie de Henan Xinlianxin, etc. Nuestros paquetes de procesos completos tambi\u00e9n sirven a la ciudad de Mendeleevsk en la Rep\u00fablica de Tatarst\u00e1n, Rusia, donde se ha completado un proyecto CCUS de 40.000 toneladas\/a\u00f1o. Tenemos una posici\u00f3n dominante en este nicho en China continental, con una cuota de mercado superior al 70%.<\/p>","protected":false},"excerpt":{"rendered":"<p>Industrial gas processing requires compressors and refrigeration units for gases such as SO\u2082, CO\u2082, and Cl\u2082, with market demand remaining relatively stable. In recent years, with the rise of global temperatures, countries worldwide have successively proposed carbon peaking and carbon neutrality goals, driving the rapid growth of the CCUS (Carbon Capture, Utilization, and Storage) industry. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,67],"tags":[],"class_list":["post-5518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solution","category-energy-chemical"],"acf":{"photo_gallery":{"\u56fe\u7247\u5c55\u793a":[[]]}},"_links":{"self":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/5518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/comments?post=5518"}],"version-history":[{"count":2,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/5518\/revisions"}],"predecessor-version":[{"id":5523,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/posts\/5518\/revisions\/5523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/media\/5520"}],"wp:attachment":[{"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/media?parent=5518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/categories?post=5518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moonepc.com\/es\/wp-json\/wp\/v2\/tags?post=5518"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}